    {"id":85009,"date":"2020-07-28T16:39:37","date_gmt":"2020-07-28T16:39:37","guid":{"rendered":"https:\/\/casadecampodev.wpenginepowered.com\/blog\/12"},"modified":"2025-11-18T03:32:03","modified_gmt":"2025-11-18T03:32:03","slug":"old-airport-runway-on-teeth-of-the-dog","status":"publish","type":"post","link":"https:\/\/www.casadecampo.com.do\/es\/blog\/2020\/07\/28\/old-airport-runway-on-teeth-of-the-dog\/","title":{"rendered":"La vieja pista de aterrizaje en Teeth of the Dog\u00ae"},"content":{"rendered":"<p><\/p>\n<h4 style=\"text-align: center;\">Era incre\u00edble estar en el tee #12 y ver un enorme Boeing 727 viniendo hacia ti<\/h4>\n<p>\u201cEra tan genial cuando los golfistas que jugaban en Teeth of the Dog\u00ae levantaban la vista y ve\u00edan un enorme avi\u00f3n Boeing 727 de American Airlines despegando o aterrizando a pocos metros del campo. \u00a1Era espectacular!\u201d, recuerda Gilles Gagnon.<\/p>\n<p>Gagnon es el director senior de ventas de golf en Casa de Campo Resort &amp; Villas, as\u00ed como tambi\u00e9n el &#8220;director de golf em\u00e9rito&#8221;. A menudo llamado &#8220;la cara del golf caribe\u00f1o\u201d, en sus m\u00e1s de cuatro d\u00e9cadas como parte del hotel ha visto todo tipo de cosas, sin embargo siempre le ha encantado hablar sobre el viejo aeropuerto y su singular pista, que es una rareza en el mundo del golf, por decir lo menos.<\/p>\n<div id=\"attachment_47849\" style=\"width: 810px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-47849\" class=\"wp-image-47849 size-full\" src=\"https:\/\/www.casadecampo.com.do\/wp-content\/uploads\/2020\/04\/Aeropuerto-Punta-Aguila-10.jpg\" alt=\"American Airlines plane lands at original Casa de Campo airport\" width=\"800\" height=\"627\" \/><p id=\"caption-attachment-47849\" class=\"wp-caption-text\">Avi\u00f3n de America Airlines aterrizando en el aeropuerto originald de Casa de Campo<\/p><\/div>\n<p>La \u00fanica pista de aterrizaje del antiguo Aeropuerto Internacional Punta \u00c1guila corr\u00eda paralela a los incre\u00edbles hoyos al lado del mar en la parte posterior de Teeth of the Dog\u00ae (del 15 al 17), y al otro lado se encontraba el interior del campo considerado como la obra maestra de Pete Dye. La \u00fanica separaci\u00f3n entre la pista y el campo era una cerca blanca y puertas construidas junto a los hoyos 12 y 18 que bajaban y se bloqueaban despu\u00e9s de que la torre de control del aeropuerto tocaba una campana notificando a quienes estaban cerca que un avi\u00f3n iba a despegar o aterrizar.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-48435 size-medium\" src=\"https:\/\/www.casadecampo.com.do\/wp-content\/uploads\/2020\/05\/Aeropuerto-Punta-Aguila-Casa-de-Campo-4.jpg\" alt=\"The Old Runway at Casa de Campo\" width=\"300\" height=\"212\" \/><br \/>\n&#8220;Era incre\u00edble estar en el tee-box del n\u00famero 12 y ver un 727 que ven\u00eda hacia ti&#8221;, dice Gagnon mientras se r\u00ede de lo absurda que era la situaci\u00f3n. Los carros de golf y los peatones se alineaban a lo largo de la cerca para el espect\u00e1culo. &#8220;Todos en el resort deten\u00edan lo que estaban haciendo para ver los vuelos despegar y aterrizar&#8221;, contin\u00faa Gagnon. \u201cOcasionalmente el personal de la torre se olvidaba de tocar la campana y algunos golfistas o peatones que cruzaban la pista se sorprend\u00edan al encontrar un avi\u00f3n a punto de aterrizar encima de ellos. Afortunadamente, nunca hubo un contratiempo\u201d.<\/p>\n<p>La antigua pista se remonta a mediados de la d\u00e9cada de 1960 antes de que naciera Casa de Campo. La pista de aterrizaje original era simplemente un largo camino de tierra flanqueado por latas llenas de aceite que se pod\u00edan iluminar para ayudar a los pilotos a ver a d\u00f3nde iban en condiciones de vuelo no ideales o de noche. El aeropuerto prestaba servicios a peque\u00f1os aviones privados, as\u00ed como a aviones de carga y fumigaci\u00f3n. En 1978, fue oficialmente nombrado Aeropuerto Internacional Punta Aguila (LRM) cuando comenz\u00f3 sus operaciones comerciales.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-48437 size-medium\" src=\"https:\/\/www.casadecampo.com.do\/wp-content\/uploads\/2020\/05\/Original-LR-Airport-2.jpg\" alt=\"The Old Airport Runway at Casa de Campo\" width=\"300\" height=\"200\" \/><br \/>\nEn 1995, la pista se extendi\u00f3 a 2,000 metros y el aeropuerto comenz\u00f3 a aceptar vuelos regulares a La Romana desde Puerto Rico y Miami. La nueva pista extendida era lo suficientemente larga para aviones tan grandes como el Boeing 727. En el a\u00f1o 2000, el aeropuerto se mud\u00f3 a su ubicaci\u00f3n actual justo al norte del complejo, ya que Casa de Campo y la Rep\u00fablica Dominicana se convirtieron en un famoso destino tur\u00edstico con millones de visitantes anuales. Ahora llamado Aeropuerto Internacional de La Romana (LRM), la instalaci\u00f3n de servicio completo recibe vuelos y visitantes de todo el mundo.<\/p>\n<p>\u201cA la gente le encantaba mirar los aviones y se entristecieron cuando tomamos la antigua pista y el aeropuerto&#8221;, concluy\u00f3 Gagnon. Hoy, un remanente de la pista permanece justo en frente del tee 18 como un recordatorio de uno de los lugares m\u00e1s inusuales para aterrizar y despegar, no solo en el mundo del golf sino tambi\u00e9n en la aviaci\u00f3n.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-74764\" src=\"https:\/\/www.casadecampo.com.do\/wp-content\/uploads\/2025\/10\/AA-2230901-NARROW-BODY-1.06P-MEAL-SERVICE-2293-F-1500x1000-6b42342-300x200-1.jpg\" alt=\"American Airlines flight attendant serving a passenger\" width=\"300\" height=\"200\" \/><\/p>\n<p>\u00a1Buenas noticias para los hu\u00e9spedes y residentes de Casa de Campo! A partir del 5 de diciembre de 2024, American Airlines ofrecer\u00e1 nuevamente un vuelo diario directo desde el Aeropuerto Internacional de Miami al Aeropuerto de La Romana. Esta nueva ruta brinda a\u00fan m\u00e1s accesibilidad a Casa de Campo, facilitando que los viajeros de Estados Unidos puedan disfrutar de las instalaciones de golf de clase mundial del resort, incluido el legendario Teeth of the Dog\u00ae. Con solo un corto trayecto desde el Aeropuerto de La Romana, los hu\u00e9spedes pueden sumergirse r\u00e1pidamente en el lujo, la belleza y las experiencias \u00fanicas que Casa de Campo tiene para ofrecer. \u00a1Reserve su viaje ahora y disfrute de una escapada caribe\u00f1a incomparable con la comodidad de esta nueva conexi\u00f3n directa!<p><\/p><p><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Imagine jugando golf en Teeth of the Dog\u00ae y de repente un enorme avi\u00f3n Boeing 727 de American Airlines despega o aterriza justo al lado. \u00a1Emociones y adrenalina a tope en cada golpe!<\/p>\n","protected":false},"author":13,"featured_media":47849,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[175],"tags":[],"class_list":["post-85009","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La vieja pista de aterrizaje en Teeth of the Dog\u00ae | Casa de Campo<\/title>\n<meta name=\"description\" content=\"Hasta el a\u00f1o 2000, la \u00fanica pista del antiguo aeropuerto internacional de Punta \u00c1guila corr\u00eda paralela a los incre\u00edbles agujeros en el oc\u00e9ano en la parte posterior de Teeth of the Dog\u00ae , en un lado y el interior de la obra maestra dise\u00f1ada por Pete Dye en el otro.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.casadecampo.com.do\/es\/blog\/2020\/07\/28\/old-airport-runway-on-teeth-of-the-dog\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La vieja pista de aterrizaje en Teeth of the Dog\u00ae | Casa de Campo\" \/>\n<meta property=\"og:description\" content=\"Hasta el a\u00f1o 2000, la \u00fanica pista del antiguo aeropuerto internacional de Punta \u00c1guila corr\u00eda paralela a los incre\u00edbles agujeros en el oc\u00e9ano en la parte posterior de Teeth of the Dog\u00ae , en un lado y el interior de la obra maestra dise\u00f1ada por Pete Dye en el otro.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.casadecampo.com.do\/es\/blog\/2020\/07\/28\/old-airport-runway-on-teeth-of-the-dog\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa de Campo\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-28T16:39:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-18T03:32:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.casadecampo.com.do\/wp-content\/uploads\/2020\/04\/Aeropuerto-Punta-Aguila-10.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gitti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gitti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La vieja pista de aterrizaje en Teeth of the Dog\u00ae | Casa de Campo","description":"Hasta el a\u00f1o 2000, la \u00fanica pista del antiguo aeropuerto internacional de Punta \u00c1guila corr\u00eda paralela a los incre\u00edbles agujeros en el oc\u00e9ano en la parte posterior de Teeth of the Dog\u00ae , en un lado y el interior de la obra maestra dise\u00f1ada por Pete Dye en el otro.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.casadecampo.com.do\/es\/blog\/2020\/07\/28\/old-airport-runway-on-teeth-of-the-dog\/","og_locale":"es_ES","og_type":"article","og_title":"La vieja pista de aterrizaje en Teeth of the Dog\u00ae | Casa de Campo","og_description":"Hasta el a\u00f1o 2000, la \u00fanica pista del antiguo aeropuerto internacional de Punta \u00c1guila corr\u00eda paralela a los incre\u00edbles agujeros en el oc\u00e9ano en la parte posterior de Teeth of the Dog\u00ae , en un lado y el interior de la obra maestra dise\u00f1ada por Pete Dye en el otro.","og_url":"https:\/\/www.casadecampo.com.do\/es\/blog\/2020\/07\/28\/old-airport-runway-on-teeth-of-the-dog\/","og_site_name":"Casa de Campo","article_published_time":"2020-07-28T16:39:37+00:00","article_modified_time":"2025-11-18T03:32:03+00:00","og_image":[{"width":800,"height":627,"url":"https:\/\/www.casadecampo.com.do\/wp-content\/uploads\/2020\/04\/Aeropuerto-Punta-Aguila-10.jpg","type":"image\/jpeg"}],"author":"Gitti","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gitti","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.casadecampo.com.do\/es\/blog\/2020\/07\/28\/old-airport-runway-on-teeth-of-the-dog\/#article","isPartOf":{"@id":"https:\/\/www.casadecampo.com.do\/es\/blog\/2020\/07\/28\/old-airport-runway-on-teeth-of-the-dog\/"},"author":{"name":"Gitti","@id":"https:\/\/www.casadecampo.com.do\/es\/#\/schema\/person\/72a4f228410910dc82653cc3c69fc496"},"headline":"La vieja pista de aterrizaje en Teeth of the Dog\u00ae","datePublished":"2020-07-28T16:39:37+00:00","dateModified":"2025-11-18T03:32:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.casadecampo.com.do\/es\/blog\/2020\/07\/28\/old-airport-runway-on-teeth-of-the-dog\/"},"wordCount":815,"commentCount":0,"publisher":{"@id":"https:\/\/www.casadecampo.com.do\/es\/#organization"},"image":{"@id":"https:\/\/www.casadecampo.com.do\/es\/blog\/2020\/07\/28\/old-airport-runway-on-teeth-of-the-dog\/#primaryimage"},"thumbnailUrl":"https:\/\/www.casadecampo.com.do\/wp-content\/uploads\/2020\/04\/Aeropuerto-Punta-Aguila-10.jpg","articleSection":["Blog"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.casadecampo.com.do\/es\/blog\/2020\/07\/28\/old-airport-runway-on-teeth-of-the-dog\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.casadecampo.com.do\/es\/blog\/2020\/07\/28\/old-airport-runway-on-teeth-of-the-dog\/","url":"https:\/\/www.casadecampo.com.do\/es\/blog\/2020\/07\/28\/old-airport-runway-on-teeth-of-the-dog\/","name":"La vieja pista de aterrizaje en Teeth of the Dog\u00ae | Casa de Campo","isPartOf":{"@id":"https:\/\/www.casadecampo.com.do\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.casadecampo.com.do\/es\/blog\/2020\/07\/28\/old-airport-runway-on-teeth-of-the-dog\/#primaryimage"},"image":{"@id":"https:\/\/www.casadecampo.com.do\/es\/blog\/2020\/07\/28\/old-airport-runway-on-teeth-of-the-dog\/#primaryimage"},"thumbnailUrl":"https:\/\/www.casadecampo.com.do\/wp-content\/uploads\/2020\/04\/Aeropuerto-Punta-Aguila-10.jpg","datePublished":"2020-07-28T16:39:37+00:00","dateModified":"2025-11-18T03:32:03+00:00","description":"Hasta el a\u00f1o 2000, la \u00fanica pista del antiguo aeropuerto internacional de Punta \u00c1guila corr\u00eda paralela a los incre\u00edbles agujeros en el oc\u00e9ano en la parte posterior de Teeth of the Dog\u00ae , en un lado y el interior de la obra maestra dise\u00f1ada por Pete Dye en el otro.","breadcrumb":{"@id":"https:\/\/www.casadecampo.com.do\/es\/blog\/2020\/07\/28\/old-airport-runway-on-teeth-of-the-dog\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.casadecampo.com.do\/es\/blog\/2020\/07\/28\/old-airport-runway-on-teeth-of-the-dog\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.casadecampo.com.do\/es\/blog\/2020\/07\/28\/old-airport-runway-on-teeth-of-the-dog\/#primaryimage","url":"https:\/\/www.casadecampo.com.do\/wp-content\/uploads\/2020\/04\/Aeropuerto-Punta-Aguila-10.jpg","contentUrl":"https:\/\/www.casadecampo.com.do\/wp-content\/uploads\/2020\/04\/Aeropuerto-Punta-Aguila-10.jpg","width":800,"height":627,"caption":"American Airlines plane lands at original Casa de Campo airport"},{"@type":"BreadcrumbList","@id":"https:\/\/www.casadecampo.com.do\/es\/blog\/2020\/07\/28\/old-airport-runway-on-teeth-of-the-dog\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.casadecampo.com.do\/es\/"},{"@type":"ListItem","position":2,"name":"La vieja pista de aterrizaje en Teeth of the Dog\u00ae"}]},{"@type":"WebSite","@id":"https:\/\/www.casadecampo.com.do\/es\/#website","url":"https:\/\/www.casadecampo.com.do\/es\/","name":"Casa de Campo","description":"The most exclusive resort in the Caribbean","publisher":{"@id":"https:\/\/www.casadecampo.com.do\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.casadecampo.com.do\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.casadecampo.com.do\/es\/#organization","name":"Casa de Campo Resort & Villas","url":"https:\/\/www.casadecampo.com.do\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.casadecampo.com.do\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.casadecampo.com.do\/wp-content\/uploads\/2026\/06\/apple-touch-icon-favicon.png","contentUrl":"https:\/\/www.casadecampo.com.do\/wp-content\/uploads\/2026\/06\/apple-touch-icon-favicon.png","width":180,"height":180,"caption":"Casa de Campo Resort & Villas"},"image":{"@id":"https:\/\/www.casadecampo.com.do\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.casadecampo.com.do\/es\/#\/schema\/person\/72a4f228410910dc82653cc3c69fc496","name":"Gitti","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/cd85fb5f348674961171f377d78a2ecef0e9dd19da319637869b98ea82ce39dc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd85fb5f348674961171f377d78a2ecef0e9dd19da319637869b98ea82ce39dc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd85fb5f348674961171f377d78a2ecef0e9dd19da319637869b98ea82ce39dc?s=96&d=mm&r=g","caption":"Gitti"}}]}},"_links":{"self":[{"href":"https:\/\/www.casadecampo.com.do\/es\/wp-json\/wp\/v2\/posts\/85009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.casadecampo.com.do\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.casadecampo.com.do\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.casadecampo.com.do\/es\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.casadecampo.com.do\/es\/wp-json\/wp\/v2\/comments?post=85009"}],"version-history":[{"count":0,"href":"https:\/\/www.casadecampo.com.do\/es\/wp-json\/wp\/v2\/posts\/85009\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.casadecampo.com.do\/es\/wp-json\/wp\/v2\/media\/47849"}],"wp:attachment":[{"href":"https:\/\/www.casadecampo.com.do\/es\/wp-json\/wp\/v2\/media?parent=85009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.casadecampo.com.do\/es\/wp-json\/wp\/v2\/categories?post=85009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.casadecampo.com.do\/es\/wp-json\/wp\/v2\/tags?post=85009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}